{"id":13257,"date":"2009-12-16T12:34:39","date_gmt":"2009-12-16T12:34:39","guid":{"rendered":"http:\/\/www.ojobuscador.com\/?p=13257"},"modified":"2009-12-16T12:34:39","modified_gmt":"2009-12-16T12:34:39","slug":"google-comienza-el-soporte-cross-domain-al-tag-canonical","status":"publish","type":"post","link":"https:\/\/www.ojo.es\/ojobuscador\/google-comienza-el-soporte-cross-domain-al-tag-canonical\/","title":{"rendered":"Google comienza el soporte \u00abcross-domain\u00bb al tag-canonical"},"content":{"rendered":"<p>En alguna ocasi\u00f3n hemos hablado del tag-canonical y ahora parece que <a href=\"https:\/\/support.google.com\/webmasters\/answer\/139066\">Google va a empezar a dar soporte al tag \u00abentre dominios\u00bb<\/a>. Hay que tener en cuenta que en muchas ocasiones hay sitios que no permiten un cambio con una redirecci\u00f3n 301, y esta ser\u00eda una forma de solventar ese detalle.<\/p>\n<p>Adem\u00e1s, muchos usuarios tampoco tienen los conocimientos como para hacer este tipo de gestiones. Adem\u00e1s, este sistema tambi\u00e9ns ervir\u00eda para ir migrando los buscadores al nuevo sitio, y el tr\u00e1fico directo mantenerlo en la direcci\u00f3n antigua&#8230;<\/p>\n<p>Con este cambio, que probablemente funcione sin problema si est\u00e1 todo verificado correctamente en Webmaster Tools, los cambios podr\u00e1n hacerse de forma r\u00e1pida y sencilla.<\/p>\n<p>En la versi\u00f3n en espa\u00f1ol a\u00fan dice:<\/p>\n<blockquote><p>\u00c2\u00bfSe puede utilizar rel=\u00bbcanonical\u00bb para sugerir una URL can\u00f3nica de un dominio completamente distinto?<\/p>\n<p>No, para realizar la migraci\u00f3n a un dominio distinto, es m\u00e1s adecuado utilizar redireccionamientos (301) permanentes. Google tiene en cuenta actualmente las sugerencias de canonicalizaci\u00f3n entre subdominios (o dentro de un mismo dominio), pero no entre distintos dominios. Por tanto, los propietarios de los sitios web pueden especificar, por ejemplo, una p\u00e1gina can\u00f3nica de www.example.com elegida entre un conjunto de p\u00e1ginas de example.com o de help.example.com, pero no de example-widgets.com.<\/p><\/blockquote>\n<p>pero la versi\u00f3n inglesa s\u00ed que dice:<\/p>\n<blockquote><p>Can rel=\u00bbcanonical\u00bb be used to suggest a canonical url on a completely different domain?<\/p>\n<p>There are situations where it&#8217;s not easily possible to set up redirects. This could be the case when you need to migrate to a new domain name using a web server that cannot create server-side redirects. In this case, you can use the rel=\u00bbcanonical\u00bb link element to specify the exact URL of the domain preferred for indexing. While the rel=\u00bbcanonical\u00bb link element is seen as a hint and not an absolute directive, we do try to follow it where possible.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>En alguna ocasi\u00f3n hemos hablado del tag-canonical y ahora parece que Google va a empezar a dar soporte al tag \u00abentre dominios\u00bb. Hay que tener en cuenta que en muchas ocasiones hay sitios que no permiten un cambio con una redirecci\u00f3n 301, y esta ser\u00eda una forma de solventar ese detalle. Adem\u00e1s, muchos usuarios tampoco &#8230; <a title=\"Google comienza el soporte \u00abcross-domain\u00bb al tag-canonical\" class=\"read-more\" href=\"https:\/\/www.ojo.es\/ojobuscador\/google-comienza-el-soporte-cross-domain-al-tag-canonical\/\" aria-label=\"Leer m\u00e1s sobre Google comienza el soporte \u00abcross-domain\u00bb al tag-canonical\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13257","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.ojo.es\/ojobuscador\/wp-json\/wp\/v2\/posts\/13257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ojo.es\/ojobuscador\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ojo.es\/ojobuscador\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ojo.es\/ojobuscador\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ojo.es\/ojobuscador\/wp-json\/wp\/v2\/comments?post=13257"}],"version-history":[{"count":0,"href":"https:\/\/www.ojo.es\/ojobuscador\/wp-json\/wp\/v2\/posts\/13257\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ojo.es\/ojobuscador\/wp-json\/wp\/v2\/media?parent=13257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ojo.es\/ojobuscador\/wp-json\/wp\/v2\/categories?post=13257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ojo.es\/ojobuscador\/wp-json\/wp\/v2\/tags?post=13257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}