{"id":8305,"date":"2009-09-14T16:40:42","date_gmt":"2009-09-14T14:40:42","guid":{"rendered":"http:\/\/www.ojointernet.com\/?p=8305"},"modified":"2009-09-14T16:40:42","modified_gmt":"2009-09-14T14:40:42","slug":"skype-prepara-su-nueva-filosofia-de-vida","status":"publish","type":"post","link":"https:\/\/www.ojo.es\/ojointernet\/skype-prepara-su-nueva-filosofia-de-vida\/","title":{"rendered":"Skype prepara su nueva filosof\u00eda de vida"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ojo.es\/ojointernet\/wp-content\/uploads\/sites\/4\/2019\/05\/skype2.jpg\" alt=\"skype\" title=\"skype\" width=\"150\" height=\"75\" class=\"alignleft size-full wp-image-8127\" align=\"left\" \/>A\u00fan no est\u00e1 claro si Skype se vender\u00e1 o seguir\u00e1 en manos de eBay, aunque s\u00ed est\u00e1 claro es que el funcionamiento de la plataforma va a cambiar radicalmente en futuras versiones, quiz\u00e1 m\u00e1s del protocolo que del cliente que todos conocen.<\/p>\n<p>Y es que el problema de rentabilidad de Skype contin\u00faa y hace unos d\u00edas se decidi\u00f3 que <a href=\"https:\/\/gigaom.com\/2009\/09\/11\/419-skype-pulls-plug-on-third-party-extras-program\/\">el sistema de Extras se daba por finalizado<\/a>, ya que no reporta ninguna mejora a la rentabilidad del servicio. Adem\u00e1s, <a href=\"https:\/\/techcrunch.com\/2009\/09\/13\/skype-says-next-generation-platform-will-embrace-developers\/\">el sistema podr\u00eda comenzar a abrirse con nuevos elementos<\/a>, como servicios web que permitan las llamadas sin necesidad de instalar el cliente, o la integraci\u00f3n con otros protocolos abiertos.<\/p>\n<p>Ahora s\u00f3lo queda esperar a ver si la compa\u00f1\u00eda cambia de manos, y la vida de uno de los productos m\u00e1s interesantes de la red no acaba en la basura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A\u00fan no est\u00e1 claro si Skype se vender\u00e1 o seguir\u00e1 en manos de eBay, aunque s\u00ed est\u00e1 claro es que el funcionamiento de la plataforma va a cambiar radicalmente en futuras versiones, quiz\u00e1 m\u00e1s del protocolo que del cliente que todos conocen. Y es que el problema de rentabilidad de Skype contin\u00faa y hace unos &#8230; <a title=\"Skype prepara su nueva filosof\u00eda de vida\" class=\"read-more\" href=\"https:\/\/www.ojo.es\/ojointernet\/skype-prepara-su-nueva-filosofia-de-vida\/\" aria-label=\"Leer m\u00e1s sobre Skype prepara su nueva filosof\u00eda de vida\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8305","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.ojo.es\/ojointernet\/wp-json\/wp\/v2\/posts\/8305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ojo.es\/ojointernet\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ojo.es\/ojointernet\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ojo.es\/ojointernet\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ojo.es\/ojointernet\/wp-json\/wp\/v2\/comments?post=8305"}],"version-history":[{"count":0,"href":"https:\/\/www.ojo.es\/ojointernet\/wp-json\/wp\/v2\/posts\/8305\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ojo.es\/ojointernet\/wp-json\/wp\/v2\/media?parent=8305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ojo.es\/ojointernet\/wp-json\/wp\/v2\/categories?post=8305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ojo.es\/ojointernet\/wp-json\/wp\/v2\/tags?post=8305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}